{"id":974,"date":"2020-04-20T08:00:23","date_gmt":"2020-04-20T11:00:23","guid":{"rendered":"https:\/\/aiqon.com.br\/blog\/?p=974"},"modified":"2021-07-16T14:52:08","modified_gmt":"2021-07-16T17:52:08","slug":"5-licoes-aprendidas-ao-implementar-100-milhoes-de-patches","status":"publish","type":"post","link":"https:\/\/aiqon.com.br\/blog\/5-licoes-aprendidas-ao-implementar-100-milhoes-de-patches\/","title":{"rendered":"5 Li\u00e7\u00f5es aprendidas ao implementar 100 milh\u00f5es de patches"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Com mais de 100 milh\u00f5es de patches implementados, veja o nosso top 5 de li\u00e7\u00f5es ao implementar patches ao longo da d\u00e9cada.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Nesse Artigo<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/aiqon.com.br\/blog\/5-licoes-aprendidas-ao-implementar-100-milhoes-de-patches\/#Uma_historia_sobre_patching\" >Uma hist\u00f3ria sobre patching<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/aiqon.com.br\/blog\/5-licoes-aprendidas-ao-implementar-100-milhoes-de-patches\/#1_%E2%80%93_Patching_e_essencial_mesmo_que_voce_tenha_um_antivirus_instalado_e_atualizado\" >1 \u2013 Patching \u00e9 essencial mesmo que voc\u00ea tenha um antiv\u00edrus instalado e atualizado.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/aiqon.com.br\/blog\/5-licoes-aprendidas-ao-implementar-100-milhoes-de-patches\/#2_%E2%80%93_Realizando_e_registrando_evidencias_de_teste\" >2 &#8211; Realizando e registrando evid\u00eancias de teste<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/aiqon.com.br\/blog\/5-licoes-aprendidas-ao-implementar-100-milhoes-de-patches\/#3_%E2%80%93_Implementacao\" >3 \u2013 Implementa\u00e7\u00e3o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/aiqon.com.br\/blog\/5-licoes-aprendidas-ao-implementar-100-milhoes-de-patches\/#4_%E2%80%93_Mudanca_de_gestao\" >4 \u2013 Mudan\u00e7a de gest\u00e3o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/aiqon.com.br\/blog\/5-licoes-aprendidas-ao-implementar-100-milhoes-de-patches\/#5_%E2%80%93_Relatorios_e_percepcao\" >5 \u2013 Relat\u00f3rios e percep\u00e7\u00e3o<\/a><\/li><\/ul><\/nav><\/div>\n\n<h2><span class=\"ez-toc-section\" id=\"Uma_historia_sobre_patching\"><\/span>Uma hist\u00f3ria sobre patching<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Era uma tarde fria de dezembro de 2008. Um cliente, um dos maiores pontos de venda do Reino Unido, sofreu uma brecha de seguran\u00e7a.<\/p>\n<p>O v\u00edrus Down-n-up, tamb\u00e9m conhecido como Conficker, infectou um dos servidores remotos e se espalhou rapidamente atrav\u00e9s de praticamente todos os servidores e esta\u00e7\u00f5es de trabalho. As 48 horas seguintes foram gastas na execu\u00e7\u00e3o de um \u201cConficker killer\u201d em todos os dispositivos seguidos de uma reinicializa\u00e7\u00e3o. O v\u00edrus foi praticamente erradicado, por\u00e9m, eles falharam em instalar os KB958644, KB957097 e o KB958687.<\/p>\n<p>Ent\u00e3o, logo em seguida, o v\u00edrus voltou.<\/p>\n<p>Comparado as infec\u00e7\u00f5es recentes, o conficker n\u00e3o rouba ou n\u00e3o sequestra seus dados como o ransomware, mas lentamente drenava recursos que poderiam destruir o sistema operacional e for\u00e7ar uma tela azul. Essa interrup\u00e7\u00e3o ao usu\u00e1rio final deveria ser resolvida o mais r\u00e1pido poss\u00edvel.<\/p>\n<p>A rea\u00e7\u00e3o inicial do diretor de TI foi de preparar uma tarefa de patch para atualizar o ambiente. A ferramenta utilizada estava agendada para instalar tudo naquela noite. A estrat\u00e9gia n\u00e3o funcionou, e foi quando n\u00f3s fomos chamados para resolver a situa\u00e7\u00e3o, onde entramos com nossos servi\u00e7os de gerenciamento de patch e sanamos o problema.<\/p>\n<p>Ap\u00f3s mais de 10 anos, 100 milh\u00f5es de patches implementados e centenas de clientes levando a nossa marca dentro de seus ambientes, nenhum deles sofreu nenhum tipo de brecha.<\/p>\n<p>Aqui est\u00e3o nossas 5 maiores li\u00e7\u00f5es que aprendemos na \u00faltima d\u00e9cada em rela\u00e7\u00e3o aos servi\u00e7os de gerenciamento de patch.<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"1_%E2%80%93_Patching_e_essencial_mesmo_que_voce_tenha_um_antivirus_instalado_e_atualizado\"><\/span>1 \u2013 Patching \u00e9 essencial mesmo que voc\u00ea tenha um antiv\u00edrus instalado e atualizado.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Os experts da ind\u00fastria estimam que o <u>n\u00famero de brechas aumentou em cerca de 60% em 2019<\/u>, e que as infec\u00e7\u00f5es especificas de ransomware aumentaram em 90% resultando em U$11,5 bilh\u00f5es.<\/p>\n<p>Diversos diretores de T.I s\u00eanior, CIOs e CISOs acreditam que a prote\u00e7\u00e3o do seu pr\u00f3prio per\u00edmetro, incluindo prote\u00e7\u00e3o de firewall e antiv\u00edrus\/antispyware, manter\u00e1 todo o ambiente seguro. Entretanto, \u00e9 desta forma que o roubo de dados e a intrus\u00e3o na rede e sistemas ocorrem. Uma vez que uma brecha apare\u00e7a, a explora\u00e7\u00e3o sofisticada destas brechas \u00e9 f\u00e1cil de se fazer, mas extremamente dif\u00edceis de rastrear ou remediar.<\/p>\n<p>N\u00f3s seguimos um experimento simples conduzido por um grupo de estudantes do Reino Unido. Eles montaram diversos laborat\u00f3rios utilizando Windows, Linux e Mac OS protegidos com firewall e ferramentas de antiv\u00edrus\/antispyware, por\u00e9m sem nenhuma atualiza\u00e7\u00e3o no sistema operacional. Todas as esta\u00e7\u00f5es tinham acesso \u00e0 internet atrav\u00e9s de um endere\u00e7o IP roteado. Cada sistema foi deixado \u201cdo jeito que vieram\u201d sem atualiza\u00e7\u00f5es, patches ou <em>hotfixes<\/em> e ficaram ligados durante 720 horas, qualquer uma delas seria v\u00edtima de um ataque externo. Os resultados a seguir foram surpreendentes e assustadores ao mesmo tempo:<\/p>\n<table width=\"496\">\n<tbody>\n<tr>\n<td width=\"158\">\n<p style=\"text-align: center;\"><strong>Sistema Operacional<\/strong><\/p>\n<\/td>\n<td style=\"text-align: left;\" width=\"131\">\n<p style=\"text-align: center;\"><strong>Exposta\/Infectada<\/strong><\/p>\n<\/td>\n<td style=\"text-align: left;\" width=\"207\">\n<p style=\"text-align: center;\"><strong>Notas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"158\">\n<p style=\"text-align: center;\">Windows 7<\/p>\n<\/td>\n<td width=\"131\">\n<p style=\"text-align: center;\">Sim<\/p>\n<\/td>\n<td width=\"207\">\n<p style=\"text-align: center;\">Infectada pelo Windows 2012<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"158\">\n<p style=\"text-align: center;\">Windows 10<\/p>\n<\/td>\n<td width=\"131\">\n<p style=\"text-align: center;\">Sim<\/p>\n<\/td>\n<td width=\"207\">\n<p style=\"text-align: center;\">Infectada pelo Windows 2012<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"158\">\n<p style=\"text-align: center;\">Windows Server 2012<\/p>\n<\/td>\n<td width=\"131\">\n<p style=\"text-align: center;\">Sim<\/p>\n<\/td>\n<td width=\"207\">\n<p style=\"text-align: center;\">Explorada usando RDP<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"158\">\n<p style=\"text-align: center;\">Windows Server 2016<\/p>\n<\/td>\n<td width=\"131\">\n<p style=\"text-align: center;\">N\u00e3o<\/p>\n<\/td>\n<td width=\"207\"><\/td>\n<\/tr>\n<tr>\n<td width=\"158\">\n<p style=\"text-align: center;\">Mac OS \u201cMojave\u201d<\/p>\n<\/td>\n<td width=\"131\">\n<p style=\"text-align: center;\">N\u00e3o<\/p>\n<\/td>\n<td width=\"207\"><\/td>\n<\/tr>\n<tr>\n<td width=\"158\">\n<p style=\"text-align: center;\">Linux Ubuntu 14<\/p>\n<\/td>\n<td width=\"131\">\n<p style=\"text-align: center;\">N\u00e3o<\/p>\n<\/td>\n<td width=\"207\"><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: left;\" width=\"158\">\n<p style=\"text-align: center;\">Linux SUSE<\/p>\n<\/td>\n<td style=\"text-align: left;\" width=\"131\">\n<p style=\"text-align: center;\">N\u00e3o<\/p>\n<\/td>\n<td width=\"207\">\n<p style=\"text-align: left;\">\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Antes da destrui\u00e7\u00e3o do laborat\u00f3rio, evid\u00eancia forense foi coleta para demonstrar que o RDP foi usado para explora\u00e7\u00e3o ransomware no Windows Server 2012 e em ambos os desktops virtuais Windows. Nenhum dos dispositivos Linux ou Mac OS foram impactados. Talvez se os experimentos tivessem durado mais, esses poderiam possivelmente ser infectados? O que podemos tirar deste experimento \u00e9 que qualquer um pode ser uma v\u00edtima mesmo com prote\u00e7\u00e3o de firewall e antiv\u00edrus\/antispyware em funcionamento<\/p>\n<h2><span class=\"ez-toc-section\" id=\"2_%E2%80%93_Realizando_e_registrando_evidencias_de_teste\"><\/span>2 &#8211; Realizando e registrando evid\u00eancias de teste<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ningu\u00e9m entende o medo de um gerente de TI quando eles ouvem a seguinte frase; \u201c<a href=\"https:\/\/aiqon.com.br\/blog\/atualizar-os-dispositivos-reflete-em-impactos-reais-nas-empresas\/\">Tem algu\u00e9m realizando as tarefas de patch agora?<\/a>\u201d<\/p>\n<p>N\u00f3s aprendemos que as atividades de patching devem ser feitas em uma plataforma transparente. N\u00f3s acreditamos que h\u00e1 uma aloca\u00e7\u00e3o perfeita de recursos que devem ser usados para testar e documentar os testes. Isto leva a menos interrup\u00e7\u00e3o ao usu\u00e1rio final e um aumento de confian\u00e7a.<\/p>\n<p>O modelo a seguir \u00e9 um exemplo do que esperamos performar rotineiramente em nossos clientes:<\/p>\n<ol>\n<li>Uma c\u00f3pia de cada sistema operacional (com Service Packs \u00fanicos\/ Feature Updates) que melhor exemplifica o ambiente real \u00e9 preparado em um laborat\u00f3rio Virtual. Todas as varia\u00e7\u00f5es devem ser testadas.<\/li>\n<li>Cada sistema operacional \u00e9 reiniciado diversas vezes para garantir que toda atividade p\u00f3s rein\u00edcio \u00e9 feita. Um dos patches que testamos em 2015 mudava o layout do teclado para Chin\u00eas. Isso s\u00f3 foi descoberto depois de diversas reinicializa\u00e7\u00f5es, e caso n\u00e3o fosse encontrado, se tornaria um pesadelo para a equipe de suporte global. Este patch em particular foi removido das implementa\u00e7\u00f5es.<\/li>\n<li>Todos os problemas s\u00e3o completamente investigados, mesmo que eles sejam vistos apenas uma vez.<\/li>\n<li>Todos os patches que cont\u00e9m arquivos de desinstala\u00e7\u00e3o s\u00e3o testados para garantir que a desinstala\u00e7\u00e3o funcione! Nem sempre confie no fabricante, esta \u00e9 uma das nossas regras de ouro<\/li>\n<li>Qualquer patch que n\u00e3o tenha uma instala\u00e7\u00e3o \u00e9 testado no m\u00ednimo duas vezes, esta \u00e9 outra das nossas regras de ouro.<\/li>\n<\/ol>\n<p>Todos os testes s\u00e3o documentados e devem ser conclu\u00eddos antes de qualquer atividade subsequente. Quaisquer problemas encontrados durante a implementa\u00e7\u00e3o, teste ou p\u00f3s-rein\u00edcio ser\u00e3o detalhados. Grande parte dos clientes ir\u00e3o querer ver essa evid\u00eancia antes de iniciarem o processo de controle de altera\u00e7\u00f5es.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"3_%E2%80%93_Implementacao\"><\/span>3 \u2013 Implementa\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A implementa\u00e7\u00e3o est\u00e1 a apenas alguns cliques de ser completa, certo? Na realidade, aqui \u00e9 onde o conhecimento do ambiente que voc\u00ea est\u00e1 trabalhando \u00e9 indispens\u00e1vel.<\/p>\n<p>Voc\u00ea terminou o teste e sabe que os patches n\u00e3o ir\u00e3o interromper os usu\u00e1rios finais. Entretanto, o que voc\u00ea n\u00e3o sabe \u00e9 como estes patches implementados \u201cem massa\u201d impactar\u00e3o na sua rede, o tempo necess\u00e1rio para instalar e os requisitos do ambiente nas suas esta\u00e7\u00f5es e servidores.<\/p>\n<p>Aqui est\u00e3o alguns dos requisitos de alto n\u00edvel que voc\u00ea precisar\u00e1 ter ou saber:<\/p>\n<ol>\n<li><strong>Listar quais patches est\u00e3o faltando por ordem de severidade<\/strong>. Determine quais patches s\u00e3o os mais importantes. Caso voc\u00ea consiga, os liste tamb\u00e9m de acordo com a <a href=\"https:\/\/aiqon.com.br\/blog\/explicar-o-cve-e-o-cvss\/\">pontua\u00e7\u00e3o de risco do CVSS<\/a> j\u00e1 que esta \u00e9 a forma mais precisa de identificar a severidade dispon\u00edvel hoje. Mantenha seu ambiente seguro.<\/li>\n<li><strong>Identifique quais patches s\u00e3o cumulativos<\/strong>. Voc\u00ea n\u00e3o precisa realizar todos os updates cr\u00edticos caso eles j\u00e1 tenham sido repostos, torne sua implementa\u00e7\u00e3o mais eficiente<\/li>\n<li><strong>Calcule o tamanho dos patches<\/strong>. H\u00e1 espa\u00e7o livre no disco das suas esta\u00e7\u00f5es e servidores? E a rede consegue suportar a implementa\u00e7\u00e3o? Planejamento aumenta a confian\u00e7a.<\/li>\n<li><strong>Cronometre a instala\u00e7\u00e3o como parte do seu teste.<\/strong> Os usu\u00e1rios podem esperar tanto tempo? Usu\u00e1rios finais felizes \u00e9 refer\u00eancia de um bom servi\u00e7o.<\/li>\n<\/ol>\n<h2><span class=\"ez-toc-section\" id=\"4_%E2%80%93_Mudanca_de_gestao\"><\/span>4 \u2013 Mudan\u00e7a de gest\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Nossos clientes n\u00e3o possu\u00edam controle de altera\u00e7\u00f5es em seus ambientes, somente clientes dos setores banc\u00e1rios, varejos e governamentais solicitaram um processo de aprova\u00e7\u00e3o formal para implementa\u00e7\u00e3o e instala\u00e7\u00e3o dos patches. Mesmo em casos que n\u00e3o seja implementada no ambiente inteiro dos nossos clientes, o sucesso do nosso servi\u00e7o \u00e9 poss\u00edvel gra\u00e7as \u00e0 sele\u00e7\u00e3o, classifica\u00e7\u00e3o dos patches e cronograma para aplica\u00e7\u00e3o.<\/p>\n<p>Estudos constataram que o gerenciamento de altera\u00e7\u00f5es normalmente \u00e9 aplicado em mais de 80% do ambiente, e no caso da FTSE 100, \u00e9 aplicado em 100% do ambiente. Nossa fun\u00e7\u00e3o \u00e9 apresentar os patches que queremos implementar, os testes que realizamos com esses patches, os resultados desses testes e buscar a aprova\u00e7\u00e3o para iniciar um laborat\u00f3rio e em seguida o in\u00edcio do projeto de implementa\u00e7\u00e3o dos patches. Isso acaba transferindo a responsabilidade, por\u00e9m garante que o cronograma seja cumprido no tempo determinado. Voc\u00ea consegue imaginar uma implementa\u00e7\u00e3o simult\u00e2nea no Reino Unido e no Jap\u00e3o?<\/p>\n<h2><span class=\"ez-toc-section\" id=\"5_%E2%80%93_Relatorios_e_percepcao\"><\/span>5 \u2013 Relat\u00f3rios e percep\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>O \u00faltimo passo, talvez o mais cr\u00edtico deles, na sua estrat\u00e9gia de patching seria relatar o sucesso obtido.\u00a0 \u00c9 importante que os gerentes superiores vejam a cobertura dos patches em todo o ambiente e a dura\u00e7\u00e3o do servi\u00e7o. Caso voc\u00ea esteja sob contrato para implementar atualiza\u00e7\u00f5es todo m\u00eas, mostre relat\u00f3rios que possam provar isso. Nada alivia mais a preocupa\u00e7\u00e3o da governan\u00e7a do que ver voc\u00ea provando mensalmente seus esfor\u00e7os com \u201cservi\u00e7o ao longo do tempo\u201d<\/p>\n<p><em>Texto em parceria com <a href=\"http:\/\/www.syxsense.com\/\">Syxsense<\/a><\/em><\/p>\n<p>Conhe\u00e7a o Syxsense<\/p>\n<figure class=\"wp-block-embed wp-block-embed-youtube is-type-video is-provider-youtube epyt-figure\"><div class=\"wp-block-embed__wrapper\"><div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  style=\"display: block; margin: 0px auto;\"  id=\"_ytid_27753\"  width=\"1140\" height=\"641\"  data-origwidth=\"1140\" data-origheight=\"641\" src=\"https:\/\/www.youtube.com\/embed\/5Ne_DpBVXUM?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=pt&iv_load_policy=3&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div><\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Com mais de 100 milh\u00f5es de patches implementados, veja o nosso top 5 de li\u00e7\u00f5es ao implementar patches ao longo da d\u00e9cada. Uma hist\u00f3ria sobre patching Era uma tarde fria de dezembro de 2008. Um cliente, um dos maiores pontos de venda do Reino Unido, sofreu uma brecha de seguran\u00e7a. O v\u00edrus Down-n-up, tamb\u00e9m conhecido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[92,91,9],"class_list":["post-974","post","type-post","status-publish","format-standard","has-post-thumbnail","category-patch-management","tag-governanca","tag-licoes","tag-patch","czr-hentry"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2020\/04\/Licoes-aprendidas-100M-patches.png","_links":{"self":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/comments?post=974"}],"version-history":[{"count":5,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/974\/revisions"}],"predecessor-version":[{"id":1829,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/974\/revisions\/1829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/media\/1828"}],"wp:attachment":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/media?parent=974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/categories?post=974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/tags?post=974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}