{"id":308,"date":"2019-09-17T20:37:43","date_gmt":"2019-09-17T20:37:43","guid":{"rendered":"https:\/\/aiqon.com.br\/blog\/?p=308"},"modified":"2020-02-06T12:34:47","modified_gmt":"2020-02-06T15:34:47","slug":"diga-adeus-aos-patches-da-versao-1703-em-outubro","status":"publish","type":"post","link":"https:\/\/aiqon.com.br\/blog\/diga-adeus-aos-patches-da-versao-1703-em-outubro\/","title":{"rendered":"Diga adeus aos patches da vers\u00e3o 1703 em outubro"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><h2 id=\"diga-adeus-aos-patches-da-vers\u00e3o-1703-em-outubro\"><span class=\"ez-toc-section\" id=\"Diga_adeus_aos_patches_da_versao_1703_em_outubro\"><\/span>Diga adeus aos patches da vers\u00e3o 1703 em outubro<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A Microsoft est\u00e1 lembrando aos administradores de TI que o Windows 10, vers\u00e3o 1703 das edi\u00e7\u00f5es Enterprise e Education, est\u00e1 chegando ao fim da vida \u00fatil em 9 de outubro de 2019.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Nesse Artigo<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/aiqon.com.br\/blog\/diga-adeus-aos-patches-da-versao-1703-em-outubro\/#Diga_adeus_aos_patches_da_versao_1703_em_outubro\" >Diga adeus aos patches da vers\u00e3o 1703 em outubro<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/aiqon.com.br\/blog\/diga-adeus-aos-patches-da-versao-1703-em-outubro\/#O_que_voce_deve_fazer_a_seguir\" >O que voc\u00ea deve fazer a seguir?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/aiqon.com.br\/blog\/diga-adeus-aos-patches-da-versao-1703-em-outubro\/#Atualizando_seu_parque\" >Atualizando seu parque<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>Isso significa que a vers\u00e3o n\u00e3o ser\u00e1 mais suportada e n\u00e3o receber\u00e1 novas atualiza\u00e7\u00f5es mensais de seguran\u00e7a ou qualidade. As vers\u00f5es de consumidor (edi\u00e7\u00f5es Home, Pro, Pro for Workstations e IoT Core) j\u00e1 chegaram ao fim da vida \u00fatil no ano passado em 8 de outubro, e n\u00e3o recebem atualiza\u00e7\u00f5es desde ent\u00e3o.<\/p>\n<p>O aviso da Microsoft n\u00e3o \u00e9 surpresa. A vers\u00e3o 1703, conhecida como \u201cCreators Update\u201d, foi lan\u00e7ada no in\u00edcio de 2017 e originalmente tinha suporte por 18 meses; no entanto, em setembro passado, a Microsoft estendeu seu per\u00edodo de manuten\u00e7\u00e3o para 30 meses nas edi\u00e7\u00f5es 1703 Enterprise e Education.<\/p>\n<p><em>\u201cN\u00e3o h\u00e1 suporte estendido dispon\u00edvel para nenhuma edi\u00e7\u00e3o do Windows 10, vers\u00e3o 1703. Portanto, ele n\u00e3o ser\u00e1 mais suportado ap\u00f3s 9 de outubro de 2019 e n\u00e3o receber\u00e1 atualiza\u00e7\u00f5es mensais de seguran\u00e7a e qualidade contendo prote\u00e7\u00f5es das amea\u00e7as de seguran\u00e7a mais recentes\u201d<\/em>, alertou a Microsoft .<\/p>\n<h2 id=\"o-que-voc\u00ea-deve-fazer-a-seguir\"><span class=\"ez-toc-section\" id=\"O_que_voce_deve_fazer_a_seguir\"><\/span>O que voc\u00ea deve fazer a seguir?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Embora a Microsoft tenha anunciado que ofereceria atualiza\u00e7\u00f5es de seguran\u00e7a cont\u00ednuas para as empresas para o sistema operacional amadurecido, as atualiza\u00e7\u00f5es gratuitas definitivamente cessar\u00e3o ap\u00f3s 14 de janeiro de 2020.<\/p>\n<p>Para aqueles que ainda est\u00e3o no Windows 10, vers\u00e3o 1703, e precisam migrar: mude para uma vers\u00e3o de atualiza\u00e7\u00e3o de recurso mais recente e suportada, como 1809, 1903 ou at\u00e9 19H2 (a ser lan\u00e7ada em setembro ou outubro deste ano). Sempre verifique novamente os recursos do terminal e se ele suporta ou n\u00e3o as vers\u00f5es mais recentes e suportadas do Windows 10. Para obter mais informa\u00e7\u00f5es sobre os pr\u00e9-requisitos do Windows 10, voc\u00ea sempre pode verificar os requisitos da Microsoft.<\/p>\n<p>Seja voc\u00ea um consumidor com uma vers\u00e3o desatualizada do Windows 10 ou Windows 7, ou um administrador corporativo pr\u00f3ximo ou at\u00e9 vers\u00f5es anteriores do Windows 10 em fim de vida, qualquer vers\u00e3o n\u00e3o suportada do Windows pode ser atacada e explorada por meio do uso de malware ou mesmo ransomware.<\/p>\n<h2 id=\"atualizando-seu-parque\"><span class=\"ez-toc-section\" id=\"Atualizando_seu_parque\"><\/span>Atualizando seu parque<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Acabamos de disponibilizar a ferramenta de <strong>Atualiza\u00e7\u00e3o do Windows 10<\/strong> no <a href=\"http:\/\/aiqon.com.br\/syxsense\">Syxsense<\/a>, e voc\u00ea pode utiliz\u00e1-la para realizar instala\u00e7\u00f5es em massa de vers\u00f5es espec\u00edficas do sistema.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-310 aligncenter\" src=\"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2020\/02\/updates-300x126.png\" alt=\"\" width=\"300\" height=\"126\" srcset=\"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2020\/02\/updates-300x126.png 300w, https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2020\/02\/updates.png 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Manter seu parque atualizado se tornou uma tarefa muito mais simples, e n\u00e3o vale a pena correr os riscos trazidos por um ambiente desatualizado.<\/p>\n<p>Em poucos passos configure a instala\u00e7\u00e3o, que pode ser agendada para um momento futuro ou inicializada imediatamente, e aguarde que as esta\u00e7\u00f5es sejam atualizadas.<\/p>\n<p>A arquitetura de alta performance do <a href=\"http:\/\/aiqon.com.br\/syxsense\">Syxsense<\/a> permite que as instala\u00e7\u00f5es sejam r\u00e1pidas e eficientes. A sua rede local s\u00f3 baixa o arquivo de instala\u00e7\u00e3o uma vez, e o distribui de forma segmentada atrav\u00e9s dos dispositivos, impedindo sobrecargas na sua infraestrutura e mantendo baixo uso de largura de banda.<\/p>\n<p><a href=\"https:\/\/lps.aiqon.com.br\/syxsense_trial\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-426 size-full\" src=\"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2019\/12\/syxsense-trial-bottom.jpg\" alt=\"trial_syxsense\" width=\"1000\" height=\"250\" srcset=\"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2019\/12\/syxsense-trial-bottom.jpg 1000w, https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2019\/12\/syxsense-trial-bottom-300x75.jpg 300w, https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2019\/12\/syxsense-trial-bottom-768x192.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diga adeus aos patches da vers\u00e3o 1703 em outubro A Microsoft est\u00e1 lembrando aos administradores de TI que o Windows 10, vers\u00e3o 1703 das edi\u00e7\u00f5es Enterprise e Education, est\u00e1 chegando ao fim da vida \u00fatil em 9 de outubro de 2019. Isso significa que a vers\u00e3o n\u00e3o ser\u00e1 mais suportada e n\u00e3o receber\u00e1 novas atualiza\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":309,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[9,11,14],"class_list":["post-308","post","type-post","status-publish","format-standard","has-post-thumbnail","category-patch-management","tag-patch","tag-syxsense","tag-windows","czr-hentry"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2020\/02\/fim-das-atualizacoes-do-windows-10.jpg","_links":{"self":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/comments?post=308"}],"version-history":[{"count":3,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/308\/revisions"}],"predecessor-version":[{"id":450,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/308\/revisions\/450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/media\/309"}],"wp:attachment":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/media?parent=308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/categories?post=308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/tags?post=308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}