{"id":2354,"date":"2021-06-15T10:13:41","date_gmt":"2021-06-15T13:13:41","guid":{"rendered":"https:\/\/aiqon.com.br\/blog\/?p=2354"},"modified":"2022-12-22T10:35:30","modified_gmt":"2022-12-22T13:35:30","slug":"os-sistemas-nao-atualizados-se-tornaram-um-dos-maiores-problemas-da-seguranca","status":"publish","type":"post","link":"https:\/\/aiqon.com.br\/blog\/os-sistemas-nao-atualizados-se-tornaram-um-dos-maiores-problemas-da-seguranca\/","title":{"rendered":"Os Sistemas N\u00e3o Atualizados se Tornaram um dos Maiores Problemas da Seguran\u00e7a?"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Brechas causadas por sistemas n\u00e3o atualizados est\u00e3o se tornando mais comuns. Isso normalmente se d\u00e1 devido ao ac\u00famulo de <a href=\"https:\/\/aiqon.com.br\/blog\/3-razoes-por-que-o-patch-e-importante\/\">patches<\/a> e os hackers tomam vantagem disso.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Nesse Artigo<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/aiqon.com.br\/blog\/os-sistemas-nao-atualizados-se-tornaram-um-dos-maiores-problemas-da-seguranca\/#Sobrecarga_de_patch\" >Sobrecarga de patch<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/aiqon.com.br\/blog\/os-sistemas-nao-atualizados-se-tornaram-um-dos-maiores-problemas-da-seguranca\/#Enderecando_a_sobrecarga_de_patch_com_automacao\" >Endere\u00e7ando a sobrecarga de patch com automa\u00e7\u00e3o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/aiqon.com.br\/blog\/os-sistemas-nao-atualizados-se-tornaram-um-dos-maiores-problemas-da-seguranca\/#Automacao_de_TI_com_o_Syxsense\" >Automa\u00e7\u00e3o de TI com o Syxsense<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>Brechas devido a sistemas n\u00e3o atualizadas s\u00e3o not\u00edcias grandes nos dias de hoje. Seis semanas ap\u00f3s a Microsoft lan\u00e7ar um patch para o Exchange Server, cerca de 10% das empresas n\u00e3o o tinham instalado ainda e os hackers se aproveitaram disso.<\/p>\n<p>Mesmo patches mais velhos s\u00e3o explorados em grande volume. Um patch do Fortinet de 2019 para os servidores VPN Fortigate continua a ser um grande alvo de ataques de ransomware. Parece que n\u00e3o h\u00e1 fim ao n\u00famero de patches de seguran\u00e7a ignorados que colocam a TI da empresa em risco.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Sobrecarga_de_patch\"><\/span>Sobrecarga de patch<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Como pode v\u00e3os de seguran\u00e7a t\u00e3o \u00f3bvios continuarem a existir por tanto tempo? Fora a neglig\u00eancia, uma raz\u00e3o pode ser a sobrecarga de patch. Em poucas semanas, tr\u00eas das maiores empresas de TI lan\u00e7aram novos patches.<\/p>\n<p>A Microsoft encontrou cerca de vulnerabilidades zero-day em uma semana. Os patches arrumaram 110 vulnerabilidades, com 19 delas classificas como cr\u00edticas. Outras 88 vulnerabilidades foram classificadas como importante. As plataformas afetadas inclu\u00edam o navegador Edge, o Azure, Azure DevOps Server, Microsoft Office, SharePoint Server, Hyper-V, Team Foundation Server, Visual Studio e Exchange Server. Provavelmente a mais cr\u00edtica dessas vulnerabilidades descobertas \u00e9 a que lida com a eleva\u00e7\u00e3o de privil\u00e9gio no Win32k que permite que os hackers consigam privil\u00e9gios nos sistemas. Enquanto isso, a Ag\u00eancia de seguran\u00e7a nacional emitiu um alerta sobre outras 4 vulnerabilidades cr\u00edticas no Exchange Server.<\/p>\n<p>Al\u00e9m disso, a Adobe lan\u00e7ou 10 patches para bugs de seguran\u00e7a, 7 dos quais s\u00e3o considerados cr\u00edticos. A Google tamb\u00e9m lan\u00e7ou a \u00faltima vers\u00e3o do seu navegador Chrome. Ele cont\u00e9m 7 corre\u00e7\u00f5es de seguran\u00e7a, incluindo uma de vulnerabilidade Zero-day.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Enderecando_a_sobrecarga_de_patch_com_automacao\"><\/span>Endere\u00e7ando a sobrecarga de patch com automa\u00e7\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Com essa grande quantidade de patches e atualiza\u00e7\u00f5es (h\u00e1 muito mais de diversas outras fontes), \u00e9 f\u00e1cil entender como a TI ficaria para tr\u00e1s. Patchs podem facilmente se acumular. A TI pode at\u00e9 ficar tentada a n\u00e3o dar valor a urg\u00eancia se eles virem os an\u00fancios de patches cr\u00edticos, mas n\u00e3o verem danos aparentes no ambiente. As vezes leva tempo para que ocorra uma brecha de seguran\u00e7a s\u00e9ria antes de entender a import\u00e2ncia de atualizar os patches.<\/p>\n<p>At\u00e9 l\u00e1, entretanto, j\u00e1 ser\u00e1 tarde demais. O que \u00e9 necess\u00e1rio \u00e9 uma \u00eanfase renovada na dilig\u00eancia e velocidade de aplica\u00e7\u00e3o de patch. Em muitos casos, isso requer uma repaginada completa nos processos de seguran\u00e7a e atualiza\u00e7\u00e3o de patch.<\/p>\n<p>Esse h\u00e1bito de testar todos os patches e instalar eles manualmente levam muito tempo e j\u00e1 n\u00e3o \u00e9 mais h\u00e1bil. \u00c9 raro uma organiza\u00e7\u00e3o que note a presen\u00e7a de um novo patch cr\u00edtico e o avalie, teste e implemente-o a tempo. A maioria das organiza\u00e7\u00f5es leva dias para fazer isso. Algumas levam semanas. E como nos casos da Fortinet VPN e do Microsoft Exchange Server, algumas nunca as fazem.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Automacao_de_TI_com_o_Syxsense\"><\/span><strong>Automa\u00e7\u00e3o de TI com o Syxsense<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A melhor forma de lidar com essa era de grande volume de atualiza\u00e7\u00e3o de patches \u00e9 automatizar o processo. Problema \u00e9 inevit\u00e1vel a n\u00e3o ser que a organiza\u00e7\u00e3o possa prover uma abund\u00e2ncia de profissionais treinados que possam analisar meticulosamente cada an\u00fancio de patch de cada fabricante, test\u00e1-los e aplic\u00e1-los imediatamente a todos os endpoints. O melhor m\u00e9todo \u00e9 deixar isso para uma ferramenta de confian\u00e7a, uma que tem o poder de lidar com todos os patches a partir do momento que eles s\u00e3o lan\u00e7ados, verificando sua autenticidade, testando-os e os liberando para distribui\u00e7\u00e3o.<\/p>\n<p>O <a href=\"https:\/\/lps.aiqon.com.br\/syxsense_trial\">Syxsense<\/a> analisa, verifica, testa e libera todos os patches at\u00e9 tr\u00eas horas depois do lan\u00e7amento. O nosso software pode implementar esses patches automaticamente para todos os dispositivos e usu\u00e1rios. Ele tamb\u00e9m cont\u00e9m a fun\u00e7\u00e3o de patch rollback quando uma das raras instancias de um patch instalado causar um problema. Lidando da forma mais efetiva poss\u00edvel a sobrecarga de patch. Liberando tamb\u00e9m a TI e o pessoal de seguran\u00e7a para cuidarem de outros assuntos urgentes na \u00e1rea de seguran\u00e7a da empresa.<\/p>\n<p><a href=\"https:\/\/lps.aiqon.com.br\/syxsense_trial\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2304 size-full\" src=\"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2022\/10\/PatchManagmentAIQONSyxsense.png\" alt=\"sistemas n\u00e3o atualizados\" width=\"800\" height=\"200\" srcset=\"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2022\/10\/PatchManagmentAIQONSyxsense.png 800w, https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2022\/10\/PatchManagmentAIQONSyxsense-300x75.png 300w, https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2022\/10\/PatchManagmentAIQONSyxsense-768x192.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brechas causadas por sistemas n\u00e3o atualizados est\u00e3o se tornando mais comuns. Isso normalmente se d\u00e1 devido ao ac\u00famulo de patches e os hackers tomam vantagem disso. Brechas devido a sistemas n\u00e3o atualizadas s\u00e3o not\u00edcias grandes nos dias de hoje. Seis semanas ap\u00f3s a Microsoft lan\u00e7ar um patch para o Exchange Server, cerca de 10% das [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2356,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[9],"class_list":["post-2354","post","type-post","status-publish","format-standard","has-post-thumbnail","category-patch-management","tag-patch","czr-hentry"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2022\/12\/businessman-hand-stop-dominoes-continuous-toppled-risk-with-copyspace.jpg","_links":{"self":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/2354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2354"}],"version-history":[{"count":2,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/2354\/revisions"}],"predecessor-version":[{"id":2357,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/2354\/revisions\/2357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/media\/2356"}],"wp:attachment":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}