{"id":1530,"date":"2020-11-30T17:24:56","date_gmt":"2020-11-30T20:24:56","guid":{"rendered":"https:\/\/aiqon.com.br\/blog\/?p=1530"},"modified":"2020-11-30T17:24:56","modified_gmt":"2020-11-30T20:24:56","slug":"a-lgpd-esta-em-vigor-mas-vazamento-de-dados-nao-param-fechem-as-torneiras","status":"publish","type":"post","link":"https:\/\/aiqon.com.br\/blog\/a-lgpd-esta-em-vigor-mas-vazamento-de-dados-nao-param-fechem-as-torneiras\/","title":{"rendered":"A LGPD est\u00e1 em vigor mas os vazamentos n\u00e3o param, fechem as torneiras!"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p style=\"font-weight: 400;\">Ok, olha eu aqui mais uma vez escrevendo sobre <a href=\"https:\/\/aiqon.com.br\/blog\/o-custo-de-um-vazamento-de-dados-e-como-pode-arruinar-o-seu-negocio\/\">vazamento<\/a> de dados e, pior, sobre dados pessoais de milh\u00f5es de brasileiros e inclusive de algumas figuras pol\u00edticas. (do Presidente, ministros e outros figur\u00f5es).<\/p>\n<p style=\"font-weight: 400;\">Eu estou ficando sem criatividade para os t\u00edtulos como no trocadilho de &#8220;parem as m\u00e1quinas&#8221; (fechem as torneiras) que na \u00e9poca de jornais impressos esta era a frase temida, pois significaria a necessidade de revisar o jornal que estava sendo impresso e que logo cedinho sairia para informar a popula\u00e7\u00e3o. Mas pense bem se n\u00e3o seria esse o momento de pararmos para revisar o que est\u00e1 acontecendo com a tecnologia e as informa\u00e7\u00f5es em meio aos compliances e leis. N\u00e3o seria a hora de parar as m\u00e1quinas e fechar as torneiras?<\/p>\n<p style=\"font-weight: 400;\">Pouco tempo atr\u00e1s tivemos o\u00a0<a href=\"https:\/\/aiqon.com.br\/blog\/ransomware-no-stj-como-as-solucoes-da-aiqon-evitariam-o-ataque\/\"><strong>STJ sendo hackeado<\/strong><\/a>, elei\u00e7\u00f5es e um novo hackeamento (sobre este n\u00e3o temos ainda muitas informa\u00e7\u00f5es). E agora o Minist\u00e9rio da Sa\u00fade com cerca de <a href=\"https:\/\/saude.estadao.com.br\/noticias\/geral,vazamento-de-senha-do-ministerio-da-saude-expoe-dados-de-16-milhoes-de-pacientes-de-covid,70003528583\">16 milh\u00f5es de pessoas<\/a> que tiveram suas informa\u00e7\u00f5es vazadas. \u00c0s vezes me pergunto qual o fetiche dos invasores com o estado? Ou ser\u00e1 que os hackeamentos de empresas\u00a0privadas n\u00e3o s\u00e3o t\u00e3o divulgados?<\/p>\n<p><strong>Relacionado<\/strong>:\u00a0<a href=\"https:\/\/aiqon.com.br\/blog\/o-custo-de-um-vazamento-de-dados-e-como-pode-arruinar-o-seu-negocio\/\">O custo de um vazamento de dados e como pode arruinar o seu neg\u00f3cio<\/a><\/p>\n<p style=\"font-weight: 400;\">Bem, o caso da vez foi um vazamento de dados e n\u00e3o uma invas\u00e3o em algum sistema super sofisticado. O que aconteceu foi que, durante uma parceira do Minist\u00e9rio da Sa\u00fade com o hospital Albert Eistein para um estudo sobre a pandemia do Covid-19, um rapaz achou que seria legal fazer um teste no GITHUB publicando uma lista de usu\u00e1rios e senhas que davam acesso aos sistemas E-SUS-VE (re\u00fane casos suspeitos e confirmados de COVID-19) e Sivep-Gripe (registra interna\u00e7\u00f5es por S\u00edndrome Respirat\u00f3ria Aguda Grave \u2014 SRAG). O nobre rapaz em sua defesa disse que seria um teste e que tinha esquecido de apagar a lista. Alguns amigos e clientes ficam bravos comigo quando falo do perigo dos sistemas de colabora\u00e7\u00e3o e que eles deveriam ser menos dependentes de ferramentas que \u00e0s vezes est\u00e3o l\u00e1 s\u00f3 para embelezar ou para servir de muleta para \u201cpregui\u00e7oso\u201d que quer tudo pronto.<\/p>\n<p><a href=\"https:\/\/lps.aiqon.com.br\/vazamento_de_dados\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1525 size-full\" src=\"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2020\/11\/culpado-vazamento-de-dados-1.gif\" alt=\"vazamento de dados\" width=\"800\" height=\"300\" \/><\/a><\/p>\n<p style=\"font-weight: 400;\">Entre as pessoas que tiveram a privacidade violada, com exposi\u00e7\u00e3o de informa\u00e7\u00f5es como CPF, endere\u00e7o, telefone e doen\u00e7as pr\u00e9-existentes, est\u00e1 o presidente Jair Bolsonaro e familiares; o ministro da Sa\u00fade, Eduardo Pazuello; outros seis titulares de minist\u00e9rios, como Onyx Lorenzoni e Damares Alves; o governador de S\u00e3o Paulo, Jo\u00e3o Doria, e mais 16 governadores, al\u00e9m dos presidentes da C\u00e2mara, Rodrigo Maia, e do Senado, Davi Alcolumbre.<\/p>\n<h2 style=\"font-weight: 400;\">E agora?<\/h2>\n<p style=\"font-weight: 400;\">Depois do estrago causado por este rapaz, eu continuo acreditando que conscientizar as pessoas sobre seguran\u00e7a e cyber security \u00e9 ainda uma das formas mais eficazes de combater vazamentos e brechas de seguran\u00e7a. Isso aconteceu em uma empresa privada que vazou dados que deveriam ser resguardados por um \u00f3rg\u00e3o p\u00fablico, o que torna a situa\u00e7\u00e3o ainda mais intrag\u00e1vel\u00a0quando falamos da <a href=\"https:\/\/aiqon.com.br\/blog\/lgpd-chegou-auditoria\/\">LGPD<\/a>. Se fosse uma empresa privada vazando dados de seus clientes \/ colaboradores, o tratamento seria diferente? J\u00e1 ter\u00edamos\u00a0uma multa milion\u00e1ria com base na LGPD? Acho que n\u00e3o vamos ter essas respostas, mas queria deixar claro que punir ainda \u00e9 uma forma de educar e prevenir que esses dados sejam tratados da forma err\u00f4nea\u00a0e desprez\u00edvel. Outro ponto importante para o p\u00f3s-vazamento, seria revogar e <a href=\"https:\/\/aiqon.com.br\/blog\/auditoria-de-seguranca-da-ti-a-chave-para-o-sucesso\/\">auditar todas as contas vazadas<\/a> de forma que seja poss\u00edvel mensurar o tamanho do preju\u00edzo e trabalhar numa corre\u00e7\u00e3o. Neste ponto, \u00e9 \u00f3bvio\u00a0que vou fazer meu jab\u00e1, pois com nossas ferramentas seria uma &#8220;m\u00e3o na roda&#8221; esse meio de campo do cyber security, seja <a href=\"https:\/\/aiqon.com.br\/auditoria-de-alteracoes\/\">auditando<\/a> ou seja protegendo contra <a href=\"https:\/\/aiqon.com.br\/ameacas-internas\/\">amea\u00e7as internas ou externas<\/a>.<\/p>\n<p style=\"font-weight: 400;\">Se bem que, no caso em que voc\u00ea d\u00e1 a chave da casa para o bandido, n\u00e3o h\u00e1 seguran\u00e7a ou c\u00e2meras\u00a0que possam impedi-lo de entrar.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ok, olha eu aqui mais uma vez escrevendo sobre vazamento de dados e, pior, sobre dados pessoais de milh\u00f5es de brasileiros e inclusive de algumas figuras pol\u00edticas. (do Presidente, ministros e outros figur\u00f5es). Eu estou ficando sem criatividade para os t\u00edtulos como no trocadilho de &#8220;parem as m\u00e1quinas&#8221; (fechem as torneiras) que na \u00e9poca de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1531,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[123,20],"tags":[87,146],"class_list":["post-1530","post","type-post","status-publish","format-standard","has-post-thumbnail","category-auditoria-de-ti","category-privacidade-de-dados","tag-coronavirus","tag-vazamento-de-dados","czr-hentry"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2020\/11\/mega-data-leak.jpg","_links":{"self":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/1530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1530"}],"version-history":[{"count":2,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/1530\/revisions"}],"predecessor-version":[{"id":1534,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/1530\/revisions\/1534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/media\/1531"}],"wp:attachment":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}