{"id":1429,"date":"2020-10-02T08:56:28","date_gmt":"2020-10-02T11:56:28","guid":{"rendered":"https:\/\/aiqon.com.br\/blog\/?p=1429"},"modified":"2020-10-01T19:34:56","modified_gmt":"2020-10-01T22:34:56","slug":"principais-elementos-para-politica-de-seguranca-de-dados-dos-clientes","status":"publish","type":"post","link":"https:\/\/aiqon.com.br\/blog\/principais-elementos-para-politica-de-seguranca-de-dados-dos-clientes\/","title":{"rendered":"Principais elementos para pol\u00edtica de seguran\u00e7a de dados dos clientes"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Uma pol\u00edtica de seguran\u00e7a de dados especifica detalhes sobre como os dados do cliente, PII de funcion\u00e1rios, propriedade intelectual e outras informa\u00e7\u00f5es sens\u00edveis devem ser manuseadas. As vezes referida como \u201cpol\u00edtica de seguran\u00e7a de dados dos clientes\u201d, mas o termo pol\u00edtica de seguran\u00e7a de dados \u00e9 mais preciso e amplo.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Nesse Artigo<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/aiqon.com.br\/blog\/principais-elementos-para-politica-de-seguranca-de-dados-dos-clientes\/#Elementos_pessoais_da_politica_de_seguranca_de_dados\" >Elementos pessoais da pol\u00edtica de seguran\u00e7a de dados<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/aiqon.com.br\/blog\/principais-elementos-para-politica-de-seguranca-de-dados-dos-clientes\/#Elementos_da_tecnologia_de_uma_politica_de_seguranca_de_dados\" >Elementos da tecnologia de uma pol\u00edtica de seguran\u00e7a de dados<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/aiqon.com.br\/blog\/principais-elementos-para-politica-de-seguranca-de-dados-dos-clientes\/#Conclusao\" >Conclus\u00e3o<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>A pol\u00edtica de seguran\u00e7a de dados deve incluir duas categorias amplas de elementos: <strong>Pol\u00edticas que se aplicam a pessoa e pol\u00edticas que se aplicam a tecnologia.<\/strong><\/p>\n<blockquote><p>Conte\u00fado relacionado: <a href=\"https:\/\/lps.aiqon.com.br\/10-questoes-para-avaliar-a-seguranca-de-dados-na-sua-empresa\">[Ebook Gratuito] 10 quest\u00f5es para avaliar a seguran\u00e7a de dados na sua empresa<\/a><\/p><\/blockquote>\n<h2><span class=\"ez-toc-section\" id=\"Elementos_pessoais_da_politica_de_seguranca_de_dados\"><\/span>Elementos pessoais da pol\u00edtica de seguran\u00e7a de dados<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Aqui est\u00e3o os principais elementos focados na pessoa para se ter em mente ao desenvolver ou revisar uma pol\u00edtica de seguran\u00e7a de dados para uma companhia:<\/p>\n<ul>\n<li><strong>Uso aceit\u00e1vel<br \/>\n<\/strong>Qualquer um que tenha logado na rede da corpora\u00e7\u00e3o nos \u00faltimos 10-15 anos provavelmente foi recebido com um pop-up de aceita\u00e7\u00e3o de pol\u00edtica de uso. A aceita\u00e7\u00e3o da pol\u00edtica de uso define o comportamento pr\u00f3prio e improprio quando os usu\u00e1rios acessam os recursos de rede da companhia, incluindo restri\u00e7\u00f5es dos recursos da companhia para atividades n\u00e3o relacionadas ao neg\u00f3cio. Ele pode detalhar tamb\u00e9m qualquer monitoramento que a companhia fa\u00e7a para garantir a aceita\u00e7\u00e3o da pol\u00edtica de uso.<\/li>\n<\/ul>\n<ul>\n<li><strong>Senhas<br \/>\n<\/strong>Estabelecer uma pol\u00edtica de senha \u00e9 outra parte b\u00e1sica de uma pol\u00edtica de seguran\u00e7a de dados. A pol\u00edtica de senhas deve claramente mostrar os requisitos de tamanho e complexidade de senhas e qual a validade delas, assim como o procedimento de resetar senhas esquecidas.<\/li>\n<\/ul>\n<ul>\n<li><strong>E-mail<br \/>\n<\/strong>Por conta dos servi\u00e7os de e-mail serem cr\u00edticos para os funcion\u00e1rios, fabricantes e clientes, sua pol\u00edtica de seguran\u00e7a de dados deve especificar detalhes sobre como o e-mail deve ser usado, se as caixas de entrada s\u00e3o criptografadas e as t\u00e9cnicas usadas para combater phishing e outros vetores de ataque que utilizam o e-mail como alvo.<\/li>\n<\/ul>\n<ul>\n<li><strong><a href=\"https:\/\/aiqon.com.br\/auditoria-de-alteracoes\/\">Auditoria<\/a><br \/>\n<\/strong>Auditar tentativas de acesso, altera\u00e7\u00f5es nas configura\u00e7\u00f5es do sistema e atividade na rede \u00e9 cr\u00edtico tanto para a seguran\u00e7a quanto para as v\u00e1rias regula\u00e7\u00f5es de conformidade desenhadas para proteger dados sens\u00edveis. As pol\u00edticas de seguran\u00e7a de dados devem falar o n\u00edvel de controle requisitado e os m\u00e9todos para atingi-lo.<\/li>\n<\/ul>\n<ul>\n<li><strong>Redes sociais<br \/>\n<\/strong>A maior parte das companhias n\u00e3o aprova o uso das redes sociais durante o expediente, mas \u00e9 necess\u00e1rio dizer explicitamente exatamente qual, caso haja, rede social \u00e9 aceit\u00e1vel.<\/li>\n<\/ul>\n<ul>\n<li><strong>Relat\u00f3rios de incidente de seguran\u00e7a<br \/>\n<\/strong>A pol\u00edtica de seguran\u00e7a de dados deve endere\u00e7ar os relat\u00f3rios e resposta a incidentes, especificando como as brechas de seguran\u00e7a dos dados foi lidada e por quem, assim como os incidentes devem ser analisados e as \u201cli\u00e7\u00f5es aprendidas\u201d que devem ser aplicadas para a preven\u00e7\u00e3o de incidentes futuros.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Elementos_da_tecnologia_de_uma_politica_de_seguranca_de_dados\"><\/span>Elementos da tecnologia de uma pol\u00edtica de seguran\u00e7a de dados<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Aqui est\u00e3o os elementos de seguran\u00e7a de dados focado na tecnologia para se ter em mente ao desenvolver ou revisar os procedimentos da pol\u00edtica de seguran\u00e7a de dados:<\/p>\n<ul>\n<li><strong>Seguran\u00e7a do sistema<br \/>\n<\/strong>Assegurar f\u00edsica e logicamente os servidores, roteadores, firewalls e outros ativos de TI \u00e9 um requisito para a maior parte das pol\u00edticas de seguran\u00e7a de dados. Garantir que voc\u00ea consiga realizar o backup, restaurar e gerenciar as configura\u00e7\u00f5es do servidor faz com que seja mais f\u00e1cil de reconstruir ou substituir um servidor que travou ou foi comprometido.<\/li>\n<\/ul>\n<ul>\n<li><strong>Gerenciamento de dispositivos moveis<br \/>\n<\/strong>A explos\u00e3o da utiliza\u00e7\u00e3o dos dispositivos moveis em ambiente corporativos apresentou um desafio formid\u00e1vel a muitas companhias. Uma op\u00e7\u00e3o \u00e9 segregar os dispositivos moveis em redes com pouco ou nenhum acesso as intranets da corpora\u00e7\u00e3o, especialmente para dispositivos moveis dos funcion\u00e1rios e convidados.<\/li>\n<\/ul>\n<ul>\n<li><strong>Criptografia<br \/>\n<\/strong>As melhores praticar requerem a pol\u00edtica de seguran\u00e7a de dados criptografe os dados, tanto em repouso quanto em tr\u00e2nsito, para que eles se tornem ileg\u00edveis por qualquer terceiro que consiga posse deles. O processo de classifica\u00e7\u00e3o de dados pode ser usado para aplicar criptografia a certos tipos de dados, como dados protegidos por regula\u00e7\u00f5es.<\/li>\n<\/ul>\n<ul>\n<li><strong><a href=\"https:\/\/aiqon.com.br\/scan-de-vulnerabilidade\">Scans de vulnerabilidade<\/a><br \/>\n<\/strong>Scan de vulnerabilidades nos softwares \u00e9 bem sofisticado e \u00e9 uma necessidade em todas as pol\u00edticas de seguran\u00e7a de dados. Em particular, garantir que as portas do firewall sejam monitoradas contra invasores \u00e9 um dos principais componentes da seguran\u00e7a de dados<\/li>\n<\/ul>\n<ul>\n<li><strong>Gerenciamento e monitoramento de controle de acesso<br \/>\n<\/strong>Implementar mecanismos compreens\u00edveis de controles de acesso para gerenciar o acesso aos dados pode ser atingido tanto por t\u00e9cnicas de hardware como de software. Por exemplo, o gerenciamento de acesso remoto e a autentica\u00e7\u00e3o de m\u00faltiplos fatores podem ajudar a proteger os dados.<\/li>\n<\/ul>\n<ul>\n<li><strong><a href=\"https:\/\/aiqon.com.br\/hardware-software\/\">Invent\u00e1rio de software<\/a>, gerenciamento de licen\u00e7a e <a href=\"https:\/\/aiqon.com.br\/patch-manager\">gerenciamento de patch<\/a><br \/>\n<\/strong><a href=\"https:\/\/lps.aiqon.com.br\/guia-patch\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-765 size-thumbnail\" src=\"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2020\/04\/Guia_Patch-150x150.png\" alt=\"pol\u00edtica de seguran\u00e7a - Patch\" width=\"150\" height=\"150\" srcset=\"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2020\/04\/Guia_Patch-150x150.png 150w, https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2020\/04\/Guia_Patch-510x510.png 510w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Manter uma contagem precisa de todos os <strong>softwares adquiridos<\/strong>, instalados e em uso \u00e9 cr\u00edtico para a manuten\u00e7\u00e3o da conformidade com os termos de licen\u00e7a e controles de custo. Scanear tanto os computadores dos usu\u00e1rios finais quanto os servidores para softwares n\u00e3o autorizados ou sem licen\u00e7a e garantir o <strong>gerenciamento de patch<\/strong> apropriado tamb\u00e9m \u00e9 cr\u00edtico para a seguran\u00e7a de dados e a conformidade com os requisitos de pol\u00edtica de privacidade de diversas regula\u00e7\u00f5es.<\/li>\n<\/ul>\n<ul>\n<li><strong>Backup, recupera\u00e7\u00e3o e recupera\u00e7\u00e3o de desastre (DR)<\/strong>Os profissionais de TI devem garantir que todos os dados tenham backup e que esse backup esteja o mais protegido poss\u00edvel. A prote\u00e7\u00e3o destes dados devem incluir seguran\u00e7a f\u00edsica e l\u00f3gica destes conjuntos de dados usando t\u00e9cnica como armazenamento fora de site e criptografia. Os backups devem ser testados e voc\u00ea deve ser capaz de recuperar os dados rapidamente. Tamb\u00e9m \u00e9 s\u00e1bio ter um ambiente dedicado para recupera\u00e7\u00e3o de desastre, idealmente um que voc\u00ea possa fazer failover quando necess\u00e1rio.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Conclusao\"><\/span>Conclus\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Como voc\u00ea pode ver, h\u00e1 muitos elementos a se considerar ao construir ou revisar a pol\u00edtica de seguran\u00e7a de dados. Tenha certeza de incluir os elementos necess\u00e1rios para o seu ambiente de TI \u00fanico, requisitos de seguran\u00e7a interna e regula\u00e7\u00f5es de aplica\u00e7\u00e3o externa, para que as pol\u00edticas ofere\u00e7am um n\u00edvel apropriado de seguran\u00e7a de dados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma pol\u00edtica de seguran\u00e7a de dados especifica detalhes sobre como os dados do cliente, PII de funcion\u00e1rios, propriedade intelectual e outras informa\u00e7\u00f5es sens\u00edveis devem ser manuseadas. As vezes referida como \u201cpol\u00edtica de seguran\u00e7a de dados dos clientes\u201d, mas o termo pol\u00edtica de seguran\u00e7a de dados \u00e9 mais preciso e amplo. A pol\u00edtica de seguran\u00e7a de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1435,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[96],"tags":[136],"class_list":["post-1429","post","type-post","status-publish","format-standard","has-post-thumbnail","category-seguranca-de-dados","tag-politica-de-seguranca","czr-hentry"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/aiqon.com.br\/blog\/wp-content\/uploads\/2020\/10\/Seg-Dados-clientes.jpg","_links":{"self":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/1429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1429"}],"version-history":[{"count":5,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/1429\/revisions"}],"predecessor-version":[{"id":1434,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/posts\/1429\/revisions\/1434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/media\/1435"}],"wp:attachment":[{"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aiqon.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}